{"id":2992,"date":"2021-04-13T12:58:00","date_gmt":"2021-04-13T10:58:00","guid":{"rendered":"https:\/\/pizzastories.le5stagioni.com\/germen-de-trigo-en-la-harina\/"},"modified":"2021-04-13T12:58:00","modified_gmt":"2021-04-13T10:58:00","slug":"germen-de-trigo-en-la-harina","status":"publish","type":"post","link":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/","title":{"rendered":"Germen de trigo en la harina"},"content":{"rendered":"\n<div class=\"stripe-one-col-media fullwidth\">\n            <img decoding=\"async\" src=\"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header.jpg\" alt=\"\" \/>\t\t<\/div>\n<div class=\"stripe-one-col-text \">\n<div class=\"text-description\">\n<p class=\"article-abstract\" style=\"text-align: center;\">El germen de trigo es rico en nutrientes y propiedades ben&eacute;ficas, pero &iquest;cu&aacute;l es la cantidad que debemos consumir cada d&iacute;a para conseguir el aporte nutricional adecuado?<\/p>\n<p>&nbsp;<\/p>\n<p>La cari&oacute;pside del trigo es el elemento m&aacute;s completo que hay en la naturaleza.&nbsp; Se compone de tres partes: la c&aacute;scara exterior, rica en salvado, sales minerales y fibra y que representa el 14,5% del grano, est&aacute; a su vez formada por 7 capas superpuestas, ricas en fibra, sobre todo insoluble, celulosa y lignina. El endospermo es la parte m&aacute;s importante en t&eacute;rminos de cantidad y representa alrededor del 80% del total. Sus componentes principales son las prote&iacute;nas (la mayor&iacute;a son gliadinas y gluteninas, que forman el gluten durante el amasado) y el almid&oacute;n, formado por cadenas de amilosa y amilopectina. El valor nutricional del trigo y de la harina resultante se debe a su alto contenido en almid&oacute;n y a su bajo contenido en grasa, lo que convierte a este cereal en un excelente alimento energ&eacute;tico.<\/p>\n<p>El endospermo contiene aproximadamente el 1-1,5% del contenido total de l&iacute;pidos del grano de trigo. Tambi&eacute;n hay tocoferoles (vitamina E) y carotenoides, que tienen un efecto antioxidante demostrado, y alb&uacute;minas y globulinas en cantidades muy peque&ntilde;as. El tercer elemento, el germen de trigo, es el m&aacute;s importante, ya que de &eacute;l se origina una nueva pl&aacute;ntula. Rica en propiedades beneficiosas para nuestro organismo, es la parte m&aacute;s peque&ntilde;a de la cari&oacute;pside y representa el 2-3 % del total.<\/p>\n<p>&nbsp;<\/p>\n<p>Este germen de trigo tiene un valor nutricional muy alto. Contiene amino&aacute;cidos, sales minerales como el f&oacute;sforo, el calcio, el zinc, el potasio y el hierro, &aacute;cidos grasos poliinsaturados, &uacute;tiles para proteger y reforzar la estructura de la c&eacute;lula, y, por &uacute;ltimo, vitaminas del grupo B y E, poderosos antioxidantes naturales.<\/p>\n<p>La cantidad de germen en el grano de trigo equivale aproximadamente al 2% del total del grano y en el proceso de molienda por cilindros se extrae normalmente el 0,2% \/ 0,3% del total.<\/p>\n<p>A partir de esta premisa, podemos admitir que las cantidades de germen que hay que consumir para un aporte nutricional cualificado son muy superiores a las contenidas en 100 g de pan elaborado con harina que contiene germen o en una pizza, cuya masa es de unos 200\/300 g por persona.<\/p>\n<\/div><\/div>\n<div class=\"stripe-one-col-text \">\n<div class=\"text-description\">\n\t<\/div>\n<\/p><\/div>\n<div class=\"stripe-one-col-media \">\n            <img decoding=\"async\" src=\"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-2.jpg\" alt=\"\" \/>\t\t<\/div>\n<div class=\"stripe-one-col-text \">\n<div class=\"text-description\">\n<p>Desde el punto de vista nutricional, el consumo del germen puede resultar ciertamente beneficioso si se acompa&ntilde;a a una dieta variada y completa en la que se preste atenci&oacute;n a los beneficios de todos los productos, no s&oacute;lo de algunos.<\/p>\n<p>En cuanto al producto, sin embargo, podemos decir que el pan y la pizza elaborados con harina que contiene germen de trigo pueden ser m&aacute;s sabrosos y fragantes, con un aroma inconfundible y un dorado m&aacute;s homog&eacute;neo debido al mejoramiento de la reacci&oacute;n de Maillard; adem&aacute;s, el germen aporta sabores y fragancias particulares y apreciables.<\/p>\n<\/div><\/div>\n<div class=\"stripe-one-col-text \">\n<div class=\"text-description\">\n\t<\/div>\n<\/p><\/div>\n<div class=\"stripe-one-col-media \">\n            <img decoding=\"async\" src=\"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-1.jpg\" alt=\"\" \/>\t\t<\/div>\n<div class=\"stripe-one-col-text \">\n<div class=\"text-description\">\n<p>El procesamiento en molinos de cilindros consiste en moler el grano y luego tamizar sus partes a trav&eacute;s del plansichter. Este proceso consiste en la separaci&oacute;n de los tres macroelementos (salvado, endospermo y germen) que componen la cari&oacute;pside. La molienda se realiza en dos etapas. Primero, el grano se rompe mediante cilindros acanalados que giran en direcciones opuestas y a velocidad diferencial para abrir la cari&oacute;pside y facilitar la separaci&oacute;n del endospermo de la parte exterior; despu&eacute;s, la remolienda convierte las part&iacute;culas restantes en harina al pasar por cilindros lisos y subsiguientes tamizados.<\/p>\n<p>Al final del proceso, se obtienen por separado la harina, el germen de trigo y el salvado. En la molienda por cilindros, normalmente se puede extraer el 0,2\/0,3% del germen de trigo contenido en el grano, lo que significa que la parte restante puede permanecer en la harina o en el salvado. Generalmente, por razones de salubridad y conservaci&oacute;n del producto, el germen se tuesta y se a&ntilde;ade a la propia harina.<\/p>\n<p>Esto se hace porque, durante la molienda por cilindros, el germen se descascara gradualmente y queda expuesto al aire en zonas m&aacute;s amplias, por lo que la posibilidad de enranciamiento es mayor que con otros tipos de molienda. Esta pr&aacute;ctica permite obtener un producto duradero que no se enrancia (cualquier producto, del caf&eacute; a las avellanas o los cereales, cuando se tuesta, conserva sus propiedades organol&eacute;pticas y su sabor durante m&aacute;s tiempo que un producto fresco que se enfrenta a un deterioro natural y tiende a enranciarse por la humedad).<\/p>\n<p>En la molienda a la piedra, el grano se aplasta y se rompe por el movimiento de la piedra horizontal, de modo que la superficie de germen expuesta al aire es menor al no descascararse. Este proceso permite retenerlo en la harina sin necesidad de tostarlo.<\/p>\n<p>El germen de trigo no utilizado en la producci&oacute;n de harina tiene varios usos: se emplea en la industria cosm&eacute;tica en la fabricaci&oacute;n de cremas hidratantes y emolientes, en el aceite de germen de trigo, como suplemento y en la alimentaci&oacute;n animal. Tambi&eacute;n se vende mucho en forma envasada, como copos amarillos que pueden consumirse al natural o a&ntilde;adirse a preparaciones dom&eacute;sticas. El uso de este valioso elemento no tiene contraindicaciones, excepto para quienes sufren de intolerancia al gluten.<\/p>\n<\/div><\/div>\n<div class=\"shared-content \">\n            \t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El germen de trigo es rico en nutrientes y propiedades beneficiosas, pero \u00bfcu\u00e1l es la cantidad que debemos consumir a diario para asegurarnos el aporte nutricional adecuado?<\/p>\n","protected":false},"author":1,"featured_media":1858,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[119],"tags":[],"class_list":["post-2992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnica-3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Germen de trigo en la harina - Pizza Stories<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Germen de trigo en la harina - Pizza Stories\" \/>\n<meta property=\"og:description\" content=\"El germen de trigo es rico en nutrientes y propiedades beneficiosas, pero \u00bfcu\u00e1l es la cantidad que debemos consumir a diario para asegurarnos el aporte nutricional adecuado?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizza Stories\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-13T10:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"647\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#\\\/schema\\\/person\\\/d29300c90b5517cd405edf2c907a69ba\"},\"headline\":\"Germen de trigo en la harina\",\"datePublished\":\"2021-04-13T10:58:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/\"},\"wordCount\":964,\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/germe-grano-header-1.jpg\",\"articleSection\":[\"T\u00e9cnica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/\",\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/\",\"name\":\"Germen de trigo en la harina - Pizza Stories\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/germe-grano-header-1.jpg\",\"datePublished\":\"2021-04-13T10:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/germe-grano-header-1.jpg\",\"contentUrl\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/germe-grano-header-1.jpg\",\"width\":1920,\"height\":647,\"caption\":\"Germen de trigo en la harina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/tecnica-3\\\/germen-de-trigo-en-la-harina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Germen de trigo en la harina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/\",\"name\":\"Pizza Stories\",\"description\":\"La community degli amanti della pizza\",\"publisher\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#organization\",\"name\":\"Pizza Stories\",\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-pizza-stories-logo.png\",\"contentUrl\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-pizza-stories-logo.png\",\"width\":512,\"height\":512,\"caption\":\"Pizza Stories\"},\"image\":{\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/#\\\/schema\\\/person\\\/d29300c90b5517cd405edf2c907a69ba\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/pizzastories.le5stagioni.com\"],\"url\":\"https:\\\/\\\/pizzastories.le5stagioni.com\\\/es\\\/author\\\/eperrone_1lnrhwgg\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Germen de trigo en la harina - Pizza Stories","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/","og_locale":"es_ES","og_type":"article","og_title":"Germen de trigo en la harina - Pizza Stories","og_description":"El germen de trigo es rico en nutrientes y propiedades beneficiosas, pero \u00bfcu\u00e1l es la cantidad que debemos consumir a diario para asegurarnos el aporte nutricional adecuado?","og_url":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/","og_site_name":"Pizza Stories","article_published_time":"2021-04-13T10:58:00+00:00","og_image":[{"width":1920,"height":647,"url":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#article","isPartOf":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/"},"author":{"name":"admin","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#\/schema\/person\/d29300c90b5517cd405edf2c907a69ba"},"headline":"Germen de trigo en la harina","datePublished":"2021-04-13T10:58:00+00:00","mainEntityOfPage":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/"},"wordCount":964,"publisher":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#organization"},"image":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg","articleSection":["T\u00e9cnica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/","url":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/","name":"Germen de trigo en la harina - Pizza Stories","isPartOf":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#primaryimage"},"image":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#primaryimage"},"thumbnailUrl":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg","datePublished":"2021-04-13T10:58:00+00:00","breadcrumb":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#primaryimage","url":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg","contentUrl":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/germe-grano-header-1.jpg","width":1920,"height":647,"caption":"Germen de trigo en la harina"},{"@type":"BreadcrumbList","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/tecnica-3\/germen-de-trigo-en-la-harina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pizzastories.le5stagioni.com\/es\/"},{"@type":"ListItem","position":2,"name":"Germen de trigo en la harina"}]},{"@type":"WebSite","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#website","url":"https:\/\/pizzastories.le5stagioni.com\/es\/","name":"Pizza Stories","description":"La community degli amanti della pizza","publisher":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pizzastories.le5stagioni.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#organization","name":"Pizza Stories","url":"https:\/\/pizzastories.le5stagioni.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/cropped-pizza-stories-logo.png","contentUrl":"https:\/\/pizzastories.le5stagioni.com\/wp-content\/uploads\/2025\/05\/cropped-pizza-stories-logo.png","width":512,"height":512,"caption":"Pizza Stories"},"image":{"@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pizzastories.le5stagioni.com\/es\/#\/schema\/person\/d29300c90b5517cd405edf2c907a69ba","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5edb4df5e2959cba313f23cb81d70d9233dad5fed62a756d80df55fa53e32990?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/pizzastories.le5stagioni.com"],"url":"https:\/\/pizzastories.le5stagioni.com\/es\/author\/eperrone_1lnrhwgg\/"}]}},"_links":{"self":[{"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/posts\/2992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/comments?post=2992"}],"version-history":[{"count":0,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/posts\/2992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/media\/1858"}],"wp:attachment":[{"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/media?parent=2992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/categories?post=2992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pizzastories.le5stagioni.com\/es\/wp-json\/wp\/v2\/tags?post=2992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}